{"id":547,"date":"2022-10-10T14:53:29","date_gmt":"2022-10-10T14:53:29","guid":{"rendered":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/?p=547"},"modified":"2025-12-09T17:33:41","modified_gmt":"2025-12-09T17:33:41","slug":"mes-pratiques-du-samedi-matin","status":"publish","type":"post","link":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/2022\/10\/10\/mes-pratiques-du-samedi-matin\/","title":{"rendered":"Mes pratiques du samedi matin"},"content":{"rendered":"\n<p>Une fois par mois, le samedi de 9h00 \u00e0 10h00, je vous propose une pratique des formes de l\u2019Art du Chi. Avec les personnes pr\u00e9sentes, on se met d\u2019accord : \u00e7a sera les 11, les 24 et\/ou les 108 postures. Et on y va ! La 1\u00e8re section des 127 pourrait aussi en faire partie, pourquoi pas\u2026<\/p>\n\n\n\n<p>Ces pratiques sont ouvertes aux \u00e9l\u00e8ves \u2013 actuels et anciens \u2013 des enseignantes et enseignants de l\u2019Art du Chi. Ce n\u2019est pas un cours, mais bien une pratique que j&rsquo;anime. Donc pour celles et ceux qui n\u2019ont encore jamais pratiqu\u00e9 avec nous, l\u2019exp\u00e9rience risque d\u2019\u00eatre un peu frustrante. Mais je ne refuserai personne !<\/p>\n\n\n\n<p>Nous pratiquons au centre de Fribourg, bien en vue, sur la terrasse du Bletz. Au c\u0153ur du quartier du Bourg, le Bletz fait face, \u00e0 la fois \u00e0 la Cath\u00e9drale St-Nicolas et \u00e0 l\u2019H\u00f4tel de Ville. Le Bletz, c\u2019est l\u2019ancien garage des tramways tout \u00e0 c\u00f4t\u00e9 de la Place Nova Fribourgo (entre les caf\u00e9s, le Rendez-Vous et les Arcades). Sur la terrasse, nous sommes prot\u00e9g\u00e9\u00b7e\u00b7s, car en surplomb par rapport \u00e0 la foule qui monte ou descend la rue de Lausanne pour se rendre au March\u00e9 du samedi matin, et de la circulation des v\u00e9hicules (autos, bus et deux-roues) entre la route des Alpes et la rue du Pont-Mur\u00e9. <\/p>\n\n\n\n<p>Et, une fois la pratique termin\u00e9e, il vous reste du temps pour faire le march\u00e9 ou aller boire un caf\u00e9&#8230;<\/p>\n\n\n\n<p>Dates des prochaines pratiques:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>5 novembre 2022<\/li><li>17 d\u00e9cembre 2022<\/li><li>14 janvier 2023<\/li><li>4 f\u00e9vrier 2023<\/li><li>11 mars 2023<\/li><li>6 mai 2023<\/li><li>3 juin 2023<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"552\" src=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/3E52CB6A-B32B-46F1-B5C2-F61DA42E806E_1_105_c.jpeg\" alt=\"Terrasse du Bletz\" class=\"wp-image-552\" srcset=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/3E52CB6A-B32B-46F1-B5C2-F61DA42E806E_1_105_c.jpeg 1024w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/3E52CB6A-B32B-46F1-B5C2-F61DA42E806E_1_105_c-300x225.jpeg 300w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/3E52CB6A-B32B-46F1-B5C2-F61DA42E806E_1_105_c-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Terrasse du Bletz<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"555\" src=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/BCA29C11-BCD3-478E-8DBE-34CB8E5F7945_1_105_c.jpeg\" alt=\"Le Bletz depuis la Place de l'H\u00f4tel de Ville\" class=\"wp-image-555\" srcset=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/BCA29C11-BCD3-478E-8DBE-34CB8E5F7945_1_105_c.jpeg 1024w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/BCA29C11-BCD3-478E-8DBE-34CB8E5F7945_1_105_c-300x225.jpeg 300w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/BCA29C11-BCD3-478E-8DBE-34CB8E5F7945_1_105_c-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Le Bletz depuis la Place de l&rsquo;H\u00f4tel de Ville<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"553\" src=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/01B13A33-F863-4E09-9439-DBA8167FDE43_1_105_c.jpeg\" alt=\"Cath\u00e9drale St-Nicolas\" class=\"wp-image-553\" srcset=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/01B13A33-F863-4E09-9439-DBA8167FDE43_1_105_c.jpeg 1024w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/01B13A33-F863-4E09-9439-DBA8167FDE43_1_105_c-300x225.jpeg 300w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/01B13A33-F863-4E09-9439-DBA8167FDE43_1_105_c-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Cath\u00e9drale St-Nicolas<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"554\" src=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/70DB74B9-EFDD-4F75-9534-921EF2B28727_1_105_c.jpeg\" alt=\"H\u00f4tel de Ville\" class=\"wp-image-554\" srcset=\"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/70DB74B9-EFDD-4F75-9534-921EF2B28727_1_105_c.jpeg 1024w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/70DB74B9-EFDD-4F75-9534-921EF2B28727_1_105_c-300x225.jpeg 300w, https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-content\/uploads\/2022\/10\/70DB74B9-EFDD-4F75-9534-921EF2B28727_1_105_c-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>H\u00f4tel de Ville<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une fois par mois, le samedi de 9h00 \u00e0 10h00, je vous propose une pratique des formes de l\u2019Art du Chi. On se met d\u2019accord, \u00e7a sera les 11, les 24 et\/ou les 108 postures. Et on y va.  [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[15,13,14],"class_list":["post-547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-du-chi","tag-qi-gong","tag-tai-chi","tag-tai-ji"],"_links":{"self":[{"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/posts\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/comments?post=547"}],"version-history":[{"count":23,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/posts\/547\/revisions"}],"predecessor-version":[{"id":775,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/posts\/547\/revisions\/775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/media\/557"}],"wp:attachment":[{"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/media?parent=547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/categories?post=547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shiatsu-tjq-fribourg.ch\/blog\/wp-json\/wp\/v2\/tags?post=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}